{"id":377362,"date":"2026-03-30T01:05:15","date_gmt":"2026-03-30T01:05:15","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-klasse-2-hgv-lgv\/"},"modified":"2026-03-30T01:05:15","modified_gmt":"2026-03-30T01:05:15","slug":"job-377350","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-377350\/","title":{"rendered":"LKW-Fahrer Klasse 2 (HGV\/LGV)"},"content":{"rendered":"<p>Stellenbezeichnung: LKW-Fahrer Klasse 2 (HGV) Startdatum: Sofort Unser Kunde: Unser langj\u00e4hriger Logistikkunde mit Sitz in Chesterfield, Derbyshire, sucht dringend LKW-Fahrer der Klasse 2 (HGV) zur regelm\u00e4\u00dfigen und fortlaufenden Verst\u00e4rkung seines Teams. Stellenbeschreibung: Die Arbeit umfasst das Fahren von LKW der Klasse 2 (HGV\/LGV), entweder f\u00fcr nationale Auslieferungen oder f\u00fcr eher lokale Eins\u00e4tze. Die Startzeiten liegen je nach Kunde zwischen 06:00 und 08:00 Uhr, so dass wir Optionen anbieten k\u00f6nnen, die Ihren spezifischen Bed\u00fcrfnissen entsprechen. Bitte besprechen Sie Ihre&#8230;<\/p>\n","protected":false},"author":155,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-377362","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJqZHHQhE7WgIReiWIMkOg-MQ","_job_required_languages":["en"],"_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Tomlin Personnel Ltd","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-tomlin-personnel-ltd\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/377362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/155"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=377362"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/377362\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=377362"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=377362"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=377362"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=377362"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=377362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}