{"id":368439,"date":"2026-03-24T01:00:57","date_gmt":"2026-03-24T01:00:57","guid":{"rendered":"https:\/\/driver-work.com\/job\/internationaler-fahrer-ce-verschiedene-arbeitssysteme-deutscher-vertrag\/"},"modified":"2026-03-24T01:00:57","modified_gmt":"2026-03-24T01:00:57","slug":"job-366899","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-366899\/","title":{"rendered":"Internationaler Fahrer C+E &#8211; verschiedene Arbeitssysteme, deutscher Vertrag"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>M\u00f6gliche Nachtarbeit: ja<\/li>\n<li>Zahlungsmethode: monatlich<\/li>\n<li>Gehaltssystem: Weihnachtsgeld<\/li>\n<\/ul>\n<h5>Ihre Aufgaben:<\/h5>\n<ul>\n<li>Transport von G\u00fctern per LKW<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>F\u00fchrerschein Klasse C+E mit Code 95<\/li>\n<li>Fahrerkarte<\/li>\n<li>Erfahrung im internationalen Transport<\/li>\n<li>Kommunikative Kenntnisse der polnischen Sprache<\/li>\n<li>Wohnsitz in Deutschland oder Polen<\/li>\n<li>Kenntnisse der europ\u00e4ischen Topographie<\/li>\n<\/ul>\n<h6>Willkommen:<\/h6>\n<ul>\n<li>Grundkenntnisse in Englisch oder Deutsch<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Besch\u00e4ftigung auf Basis eines deutschen Arbeitsvertrags &#8211; Vollzeit<\/li>\n<li>Flexible Arbeitssysteme &#8211; zugeschnitten auf die Bed\u00fcrfnisse des Fahrers<\/li>\n<li>Verf\u00fcgbare Systeme: 2&#215;1, 2&#215;2, 3&#215;1, 3&#215;2, 4&#215;1, 4&#215;2, 5&#215;1, 5&#215;2, 6&#215;1, 6&#215;2<\/li>\n<li>Stundenlohn 13,90 Euro brutto<\/li>\n<li>Zulagen (Deutschland 28 Euro, internationale Routen durchschnittlich ca. 42 Euro)<\/li>\n<li>Vorsch\u00fcsse f\u00fcr Verpflegung und Unterkunft<\/li>\n<li>Sozialleistungen<\/li>\n<li>Unterst\u00fctzung bei der Erledigung aller Formalit\u00e4ten im Zusammenhang mit der Besch\u00e4ftigung<\/li>\n<li>Krankenversicherung, die in der gesamten Europ\u00e4ischen Union g\u00fcltig ist<\/li>\n<\/ul>\n<ul>\n<li>Disposition auf Polnisch &#8211; Polnische Spediteure<\/li>\n<li>Unterst\u00fctzung durch einen polnischen Personalvermittler<\/li>\n<li>Technischer Support &#8211; technische Abteilung und autorisierter Service<\/li>\n<li>Zugang zu sozialen Einrichtungen: Duschen, ausgestattete K\u00fcchen, Waschmaschinen, Trockner an zwei Firmenstandorten<\/li>\n<li>Bonus f\u00fcr einen geworbenen Fahrer:<\/li>\n<li>150 Euro &#8211; sofort nach Unterzeichnung des Vertrags durch den Fahrer<\/li>\n<li>150 Euro &#8211; nach seinen 3 Arbeitsmonaten<\/li>\n<li>200 Euro &#8211; nach seinen 6 Arbeitsmonaten<\/li>\n<\/ul>\n<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Bitte senden Sie Ihren Lebenslauf nur auf Polnisch<\/li>\n<\/ul>\n","protected":false},"author":16906,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-368439","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Kuijpers Cargo Service GmbH &#038; Co.KG","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-kuijpers-cargo-service-gmbh-co-kg-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/368439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/16906"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=368439"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/368439\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=368439"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=368439"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=368439"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=368439"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=368439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}