{"id":360392,"date":"2026-03-20T01:02:42","date_gmt":"2026-03-20T01:02:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/kraftfahrer-kat-ce\/"},"modified":"2026-03-20T01:02:42","modified_gmt":"2026-03-20T01:02:42","slug":"job-359278","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-359278\/","title":{"rendered":"Kraftfahrer Kat. C+E"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>M\u00f6gliche Nachtarbeit: ja<\/li>\n<li>Auszahlungsmodus: monatlich<\/li>\n<\/ul>\n<h5>Dein Aufgabenbereich:<\/h5>\n<ul>\n<li>Fahrer C+E (internationaler Transport) auf K\u00dcHLTRANSPORTER<\/li>\n<li>Arbeit im Rundlauf &#8211; PL-NL-PL (manchmal auch CZ, BE, DE)<\/li>\n<li>Arbeitsvertrag<\/li>\n<li>P\u00fcnktliche Gehaltszahlungen<\/li>\n<li>Fahren in Einzelbesetzung, mit einem Auto (Auto dem Fahrer zugeordnet)<\/li>\n<li>Ehrlicher Umgang &#8211; klare Bedingungen der Zusammenarbeit &#8211; kleines Unternehmen<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>F\u00fchrerschein Kat. C+E<\/li>\n<li>Berechtigungen: Fahrerkarte, Kurs zur G\u00fcterbef\u00f6rderung und psychologische Tests<\/li>\n<li>P\u00fcnktlichkeit<\/li>\n<li>Sorgfalt im Umgang mit der anvertrauten Ausr\u00fcstung<\/li>\n<li>Berufserfahrung<\/li>\n<\/ul>\n","protected":false},"author":25102,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-360392","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"S\u0141AWOMIR P\u0104GOWSKI Przedsi\u0119biorstwo Transportowe","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-slawomir-pagowski-przedsiebiorstwo-transportowe\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/360392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/25102"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=360392"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/360392\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=360392"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=360392"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=360392"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=360392"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=360392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}