{"id":354161,"date":"2026-03-17T01:00:30","date_gmt":"2026-03-17T01:00:30","guid":{"rendered":"https:\/\/driver-work.com\/job\/fahrer-kat-c-ce-springer\/"},"modified":"2026-03-17T01:00:30","modified_gmt":"2026-03-17T01:00:30","slug":"job-352577","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-352577\/","title":{"rendered":"Fahrer Kat. C\/ C+E &#8211; Springer"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Schichtarbeit:ja<\/li>\n<li>Auszahlungsmodus:monatlich<\/li>\n<li>Besondere Berechtigungen:Aktuelle sanit\u00e4r-epidemiologische Untersuchung<\/li>\n<\/ul>\n<h5>Dein Aufgabenbereich:<\/h5>\n<ul>\n<li>t\u00e4gliche R\u00fcckkehr nach Hause<\/li>\n<li>Arbeit im Vertrieb<\/li>\n<li>nationaler Transport<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>aktuelle Untersuchungen, Fahrerkarte und Code 95 erforderlich<\/li>\n<\/ul>\n","protected":false},"author":17169,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-354161","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"MATI-TRANS sp. z o.o.","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-mati-trans-sp-z-o-o\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/354161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/17169"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=354161"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/354161\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=354161"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=354161"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=354161"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=354161"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=354161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}