{"id":323193,"date":"2026-03-01T01:01:09","date_gmt":"2026-03-01T01:01:09","guid":{"rendered":"https:\/\/driver-work.com\/job\/fahrer-kat-ce-verlader-m-w-d\/"},"modified":"2026-03-01T01:01:09","modified_gmt":"2026-03-01T01:01:09","slug":"job-322416","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-322416\/","title":{"rendered":"Fahrer Kat. C+E &#8211; Verlader (M\/W\/D)"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Schichtarbeit:ja<\/li>\n<li>Arbeitstage:Werktage (Montag &#8211; Freitag), Samstag, Sonntag, Feiertage<\/li>\n<li>M\u00f6gliche Nachtarbeit:ja<\/li>\n<li>Auszahlungsart:monatlich<\/li>\n<\/ul>\n<h5>Ihre Aufgaben:<\/h5>\n<ul>\n<li>F\u00fchren eines Lastkraftwagens im Rahmen der Abfallentsorgung<\/li>\n<li>Ausf\u00fcllen von Abfuhrpl\u00e4nen<\/li>\n<li>Be- und Entladen von Abf\u00e4llen<\/li>\n<li>Sicherstellung des guten technischen Zustands des Fahrzeugs<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>G\u00fcltiger F\u00fchrerschein der Klasse C+E<\/li>\n<li>G\u00fcltige Bescheinigung \u00fcber den Abschluss eines Kurses f\u00fcr den G\u00fcterkraftverkehr<\/li>\n<li>Fahrerkarte<\/li>\n<li>Zuverl\u00e4ssige Ausf\u00fchrung von Dienstauftr\u00e4gen und eine seri\u00f6se Einstellung zur Arbeit<\/li>\n<li>Engagement bei den \u00fcbertragenen Aufgaben<\/li>\n<li>Sorgfalt mit dem anvertrauten Fuhrpark<\/li>\n<li>P\u00fcnktlichkeit<\/li>\n<li>Flexibilit\u00e4t und Bereitschaft zur Arbeit im kontinuierlichen Schichtbetrieb, im gleichwertigen Arbeitszeitsystem, unter Ber\u00fccksichtigung der Arbeitsplanung von Montag bis Sonntag<\/li>\n<\/ul>\n<h6>W\u00fcnschenswert:<\/h6>\n<ul>\n<li>ADR-Bescheinigung<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Stabile Anstellungsbedingungen auf der Grundlage eines Arbeitsvertrags<\/li>\n<li>Marktgerechte Verg\u00fctung<\/li>\n<li>Private medizinische Versorgung, Lebens- und Unfallversicherung<\/li>\n<li>M\u00f6glichkeit zur Nutzung von Sportausweisen und Kulturkarte<\/li>\n<li>Finanzielle Unterst\u00fctzung f\u00fcr Erholung<\/li>\n<\/ul>\n<ul>\n<li>Umfangreiches Sozialpaket<\/li>\n<li>Arbeit in einer internationalen Gruppe mit hohen Standards, die sich um die Sicherheit der Mitarbeiter k\u00fcmmert<\/li>\n<li>Arbeitskleidung und individuelle Schutzausr\u00fcstung<\/li>\n<li>M\u00f6glichkeit zur beruflichen Weiterentwicklung und Finanzierung von Kursen und Schulungen f\u00fcr Berechtigungen durch den Arbeitgeber<\/li>\n<\/ul>\n","protected":false},"author":17802,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-323193","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"PreZero Service Po\u0142udnie Sp. z o.o.","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-prezero-service-poludnie-sp-z-o-o\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/323193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/17802"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=323193"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/323193\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=323193"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=323193"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=323193"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=323193"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=323193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}