{"id":317751,"date":"2026-02-25T01:04:42","date_gmt":"2026-02-25T01:04:42","guid":{"rendered":"https:\/\/driver-work.com\/job\/berufskraftfahrer-m-w-d\/"},"modified":"2026-02-25T01:04:42","modified_gmt":"2026-02-25T01:04:42","slug":"job-317745","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-317745\/","title":{"rendered":"Berufskraftfahrer (m\/w\/d)"},"content":{"rendered":"<div class=\"ba-copytext\" id=\"detail-beschreibung-text-container\">\n<p>Sind Sie gerne unterwegs und suchen einen sicheren, langfristigen Arbeitsplatz?<br \/>F\u00fcr unseren Kunden in Bad Hersfeld suchen wir engagierte Kraftfahrer (m\/w\/d) zur Unterst\u00fctzung des<br \/>bestehenden Teams.<\/p>\n<p>In dieser Position \u00fcbernehmen Sie verantwortungsvolle Fahrten in einem festen Einsatzgebiet und arbeiten mit einem modernen Fuhrpark aus MAN- und Mercedes-Fahrzeugen in einem strukturierten Umfeld.<\/p>\n<p>Freuen Sie sich auf eine gr\u00fcndliche Einarbeitung, ein kollegiales Team sowie eine T\u00e4tigkeit mit hoher<br \/>Planungssicherheit.<\/p>\n<h4>Ihre Aufgaben:<\/h4>\n<ul>\n<li>Durchf\u00fchrung von Transport- und Leerfahrten mit verschiedenen Einsatzfahrzeugen<br \/>(z.B. Hecklader, Abroll-\/Absetzkipper, Frontlader)<\/li>\n<li>Termingerechte Abholung und Lieferung von Entsorgungs- und Recyclingmaterialien<\/li>\n<li>Be- und Entladung der Fahrzeuge sowie Ladungssicherung<\/li>\n<li>Kontrolle der Frachtpapiere auf Vollst\u00e4ndigkeit und Richtigkeit<\/li>\n<li>Sorgsamer Umgang und regelm\u00e4\u00dfige Pflege des \u00fcberlassenen LKWs<\/li>\n<li>Sicherstellung der Einhaltung alle gesetzlichen Vorschriften im G\u00fcterverkehr<\/li>\n<\/ul>\n<h4>Ihr Profil:<\/h4>\n<ul>\n<li>F\u00fchrerschein Klasse C oder CE zwingend erforderlich<\/li>\n<li>Grundqualifikation Berufskraftfahrer (95) und g\u00fcltige Fahrerkarte<\/li>\n<li>Sicheres und zuverl\u00e4ssiges Fahrverhalten<\/li>\n<li>Erfahrung im Kraftverkehr w\u00fcnschenswert, aber nicht zwingend notwendig<\/li>\n<li>Selbstst\u00e4ndige, flexible und teamorientierte Arbeitsweise<\/li>\n<li>Gute Deutschkenntnisse in Wort und Schrift<\/li>\n<\/ul>\n<h4>Was wir Ihnen bieten:<\/h4>\n<ul>\n<li>Unbefristeten Arbeitsvertrag mit langfristiger Perspektive<\/li>\n<li>Geregelte Arbeitszeiten \u2013 keine Fernfahrten, gute Work\u2011Life\u2011Balance<\/li>\n<li>Moderner Fuhrpark mit Mercedes\u2011 und MAN\u2011Fahrzeugen<\/li>\n<li>Strukturierte Einarbeitung und ein unterst\u00fctzendes Teamumfeld<\/li>\n<li>Bezahlung nach Tarifvertrag<\/li>\n<li>Urlaubs- und Weihnachtsgeld<\/li>\n<li>Pers\u00f6nliche Betreuung durch Deinen Personaldienstleister<\/li>\n<\/ul>\n<h4>\u00dcber OPTIPER:<\/h4>\n<p>Als unternehmergef\u00fchrtes und mittelst\u00e4ndisches Unternehmen mit jahrzehntelanger Erfahrung in der Personaldienstleistung ist es unser Ziel, die Bed\u00fcrfnisse unserer MitarbeiterInnen mit den Anforderungen unserer Kunden bestm\u00f6glich zu verbinden. Durch eine offene, pers\u00f6nliche Kommunikation streben wir nach einer nachhaltigen und erfolgreichen Partnerschaft. Menschlich und digital.<\/p>\n<h4>Haben wir Ihr Interesse geweckt?<\/h4>\n<ul>\n<li>Dann bewerben Sie sich jetzt und Sie kommen mit nur wenigen Klicks erfolgreich zum neuen Job!<br \/>Wenn Sie noch Fragen haben, sprechen wir gerne pers\u00f6nlich \u00fcber die ausgeschriebene Stelle oder wir finden f\u00fcr Sie einen anderen Job, der zu Ihren Bed\u00fcrfnissen passt. Wir freuen uns auf Sie.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"author":24231,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-317751","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"OPTIPER Personaldienste GmbH","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-optiper-personaldienste-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/317751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/24231"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=317751"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/317751\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=317751"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=317751"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=317751"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=317751"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=317751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}