{"id":288874,"date":"2026-02-01T01:00:00","date_gmt":"2026-02-01T01:00:00","guid":{"rendered":"https:\/\/driver-work.com\/job\/internationaler-fahrer-internationale-fahrerin-kat-ce\/"},"modified":"2026-02-01T01:00:00","modified_gmt":"2026-02-01T01:00:00","slug":"job-288313","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-288313\/","title":{"rendered":"Internationaler Fahrer \/ Internationale Fahrerin Kat. C+E"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Auszahlungsmodus: monatlich<\/li>\n<\/ul>\n<h5>Ihr Aufgabenbereich:<\/h5>\n<ul>\n<li>F\u00fchren von Lastkraftwagen des Typs Tandem, Plane auf der Strecke Polen &#8211; Gro\u00dfbritannien<\/li>\n<li>Kontrolle des technischen Zustands des Fahrzeugs sowie Sorgfalt f\u00fcr dessen Sauberkeit und Funktionsf\u00e4higkeit<\/li>\n<li>Ausf\u00fcllen von Transportdokumenten und Einhaltung der Transportverfahren<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>G\u00fcltiger F\u00fchrerschein der Kategorie C+E und Fahrerkarte<\/li>\n<li>Kenntnisse der Stra\u00dfenverkehrsordnung und der Lenk- und Ruhezeiten<\/li>\n<li>Kenntnisse im Umgang mit dem Fahrtenschreiber und der F\u00fchrung von Transportdokumenten<\/li>\n<li>Flexibilit\u00e4t und Engagement<\/li>\n<\/ul>\n<h6>W\u00fcnschenswert:<\/h6>\n<ul>\n<li>Erfahrung im internationalen Transport<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Stabile Anstellung auf Basis eines Arbeitsvertrags<\/li>\n<li>Hohe Verg\u00fctung, die der vorhandenen Erfahrung entspricht<\/li>\n<\/ul>\n<ul>\n<li>Einzelbesetzungen<\/li>\n<li>Laufend gewartete Ausr\u00fcstung<\/li>\n<\/ul>\n","protected":false},"author":23058,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-288874","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"ATOB sp. z o.o.","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-atob-sp-z-o-o\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/288874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/23058"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=288874"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/288874\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=288874"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=288874"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=288874"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=288874"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=288874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}