{"id":282850,"date":"2026-01-27T01:02:27","date_gmt":"2026-01-27T01:02:27","guid":{"rendered":"https:\/\/driver-work.com\/job\/fahrer-kat-c-mit-udt-schein-m-w-d\/"},"modified":"2026-01-27T01:02:27","modified_gmt":"2026-01-27T01:02:27","slug":"job-282185","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-282185\/","title":{"rendered":"Fahrer Kat. C mit UDT-Schein (m\/w\/d)"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Schichtarbeit:nein<\/li>\n<li>Arbeitstage:Werktage (Montag &#8211; Freitag)<\/li>\n<li>M\u00f6gliche Nachtarbeit:nein<\/li>\n<li>Zahlungsmethode:monatlich<\/li>\n<li>Gehaltssystem:festes Grundgehalt + Leistungsbonus<\/li>\n<\/ul>\n<h5>Ihre Aufgaben:<\/h5>\n<ul>\n<li>Verteilung von Lebensmitteln gem\u00e4\u00df den vorgegebenen Routen<\/li>\n<li>Lieferung von Waren an Lebensmittelgesch\u00e4fte &#8211; Entladen von Lieferungen, Entgegennahme von Retouren und Reklamationen<\/li>\n<li>Bedienung eines Gabelstaplers\/Hubwagens<\/li>\n<li>Bearbeitung von Transport- und Lagerdokumentation<\/li>\n<li>Fahren eines LKW \u00fcber 3,5 t (Paletten-Solo)<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>aktuelle Tests f\u00fcr epidemiologische und sanit\u00e4re Zwecke<\/li>\n<li>F\u00fchrerschein Kat. C, Lizenz f\u00fcr den G\u00fcterkraftverkehr und Fahrerkarte<\/li>\n<li>UDT-Schein f\u00fcr Gabelstapler<\/li>\n<li>Sie haben kein Vorstrafenregister<\/li>\n<li>Verf\u00fcgbarkeit, Verantwortungsbewusstsein, Selbstst\u00e4ndigkeit &#8211; sind Ihre obersten Priorit\u00e4ten!<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Eine angenehme Arbeitsatmosph\u00e4re &#8211; freundliche Menschen und hilfsbereite F\u00fchrungskr\u00e4fte!<\/li>\n<li>Arbeitsvertrag &#8211; wir nehmen jeden Mitarbeiter ernst!<\/li>\n<li>Attraktives Gehalt &#8211; dank des Bonus, dessen H\u00f6he Sie selbst beeinflussen k\u00f6nnen!<\/li>\n<\/ul>\n<ul>\n<li>Sportpakete &#8211; Medicover Sport &#8211; denn: Ein gesunder Geist in einem gesunden K\u00f6rper!<\/li>\n<li>Zugang zur Einkaufsplattform Specja\u0142 Finanse: specjalfinanse.pl &#8211; wir unterst\u00fctzen unsere Mitarbeiter in allen Lebensbereichen!<\/li>\n<li>Ausfl\u00fcge und Integrationsveranstaltungen, dank derer wir ein starkes Team sind, das auf ein Ziel hinarbeitet<\/li>\n<\/ul>\n","protected":false},"author":16985,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-282850","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"GRUPA KAPITA\u0141OWA SPECJA\u0141","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-grupa-kapitalowa-specjal\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/282850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/16985"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=282850"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/282850\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=282850"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=282850"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=282850"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=282850"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=282850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}