{"id":281732,"date":"2026-01-26T01:01:57","date_gmt":"2026-01-26T01:01:57","guid":{"rendered":"https:\/\/driver-work.com\/job\/berufskraftfahrer-kat-ce-internationale-routen-eu-k-m\/"},"modified":"2026-01-26T01:01:57","modified_gmt":"2026-01-26T01:01:57","slug":"job-281252","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-281252\/","title":{"rendered":"Berufskraftfahrer Kat. C+E \u2013 Internationale Routen (EU) K\/M"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Auszahlungsmodus: monatlich<\/li>\n<\/ul>\n<h5>Ihr Aufgabenbereich:<\/h5>\n<ul>\n<li>Durchf\u00fchrung von Transporten auf Routen: Polen \u2013 Italien, Deutschland, \u00d6sterreich, Tschechien<\/li>\n<li>Bedienung des Gespanns: Sattelzugmaschine + Gardinenplanenauflieger (Schiebeplane) 13,6 m<\/li>\n<li>Sorgfaltspflicht f\u00fcr die anvertraute Ausr\u00fcstung und die Transportdokumentation<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>F\u00fchrerschein Kat. C+E und aktuelle Fahrerkarte<\/li>\n<li>G\u00fcltige Berechtigung (Code 95, \u00e4rztliche und psychologische Untersuchung)<\/li>\n<li>Erfahrung im internationalen Transport (w\u00fcnschenswert, aber wir ber\u00fccksichtigen auch ehrgeizige Personen zur Einarbeitung)<\/li>\n<li>Zuverl\u00e4ssigkeit, P\u00fcnktlichkeit und Sorgfalt im Umgang mit anvertrautem Eigentum<\/li>\n<\/ul>\n<h5>Das bieten wir:<\/h5>\n<ul>\n<li>Flexibles Arbeitssystem: Sie entscheiden selbst, wie lange Sie unterwegs sein m\u00f6chten. Verf\u00fcgbare Systeme: 2\/1, 3\/1, 4\/1<\/li>\n<li>Attraktive Verg\u00fctung: Basisgehalt + Di\u00e4ten\/Pauschalen (Details nach Vereinbarung im Gespr\u00e4ch, abh\u00e4ngig von Erfahrung und System)<\/li>\n<li>Moderne Flotte: Komfortables, dem Fahrer zugeordnetes Fahrzeug (Euro 6)<\/li>\n<\/ul>\n<ul>\n<li>P\u00fcnktlichkeit: Garantie f\u00fcr p\u00fcnktliche Gehaltszahlung<\/li>\n<li>Unterst\u00fctzung: St\u00e4ndige Betreuung durch einen erfahrenen Spediteur 24\/7<\/li>\n<li>Gesetzeskonformit\u00e4t: Strikte Einhaltung der Arbeits- und Ruhezeiten des Fahrers<\/li>\n<\/ul>\n","protected":false},"author":17061,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-281732","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"TEL-MET Sp. z o.o.","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-tel-met-sp-z-o-o\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/281732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/17061"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=281732"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/281732\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=281732"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=281732"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=281732"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=281732"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=281732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}