{"id":272295,"date":"2026-01-16T01:03:18","date_gmt":"2026-01-16T01:03:18","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-klasse-2-fur-saugwagen\/"},"modified":"2026-01-16T01:03:18","modified_gmt":"2026-01-16T01:03:18","slug":"job-272273","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/de\/job\/job-272273\/","title":{"rendered":"LKW-Fahrer Klasse 2 f\u00fcr Saugwagen"},"content":{"rendered":"<p>Wir suchen motivierte und qualifizierte LKW-Fahrer mit Standort bei unserem Kunden in North Kilworth &#8211; Tag- und Nachtschichten &#8211; mit Erfahrung im Fahren eines LKW Klasse 2 f\u00fcr Saugwagen. Wir bieten wettbewerbsf\u00e4hige Geh\u00e4lter und gute Arbeitsbedingungen. Tagschicht: 16,50 \u00a3 (inkl. Urlaubsanspruch) Nachtschicht: 18,00 \u00a3 (inkl. Urlaubsanspruch) Wilson Recruitment ist ein Arbeitgeber, der Chancengleichheit bietet und sich verpflichtet, M\u00f6glichkeiten unabh\u00e4ngig von Alter, Rasse, Geschlecht, Religion, ethnischer Zugeh\u00f6rigkeit und sexueller Orientierung zu bieten. \u00dcberblick: Wir suchen einen qualifizierten\u2026<\/p>\n","protected":false},"author":222,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-272295","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJqZHHQhE7WgIReiWIMkOg-MQ","_job_required_languages":["en"],"_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Wilson Recruitment Ltd","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-wilson-recruitment-ltd\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/272295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/222"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=272295"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/272295\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=272295"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=272295"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=272295"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=272295"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=272295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}