{"id":269714,"date":"2026-01-14T01:03:12","date_gmt":"2026-01-14T01:03:12","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-ce\/"},"modified":"2026-07-14T00:30:50","modified_gmt":"2026-07-14T00:30:50","slug":"job-269291","status":"expired","type":"job_listing","link":"https:\/\/driver-work.com\/de\/?post_type=job_listing&p=269714","title":{"rendered":"LKW-Fahrer C+E"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Schichtarbeit: nein<\/li>\n<li>Zahlungsmethode: monatlich<\/li>\n<li>Gehaltssystem: festes Grundgehalt + Leistungsbonus<\/li>\n<\/ul>\n<h5>Ihre Aufgaben:<\/h5>\n<ul>\n<li>Fahren eines C+E-Fahrzeugs in Westeuropa und Polen<\/li>\n<li>Durchf\u00fchrung von Lieferungen gem\u00e4\u00df dem Zeitplan und den Informationen der Logistikabteilung<\/li>\n<li>Sorgf\u00e4ltiger Umgang mit den anvertrauten Arbeitsmitteln<\/li>\n<li>Regelm\u00e4\u00dfige Lieferung und Pflege der Transportdokumentation<\/li>\n<li>Einwandfreie Vertretung des Unternehmens auf den Strecken und beim Be- und Entladen<\/li>\n<li>Einhaltung der Vorschriften bez\u00fcglich der Arbeitszeiten der Fahrer und der Stra\u00dfenverkehrsordnung<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>F\u00fchrerschein Klasse C+E<\/li>\n<li>G\u00fcltige \u00e4rztliche und psychologische Bescheinigung f\u00fcr berufliche Zwecke<\/li>\n<li>Fahrerkarte f\u00fcr digitalen Tachographen<\/li>\n<li>Mindestens 1 Jahr Erfahrung im Fahren von LKWs auf internationalen Strecken<\/li>\n<li>Bescheinigung der Berufskraftfahrerqualifikation<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Stabile Anstellung auf Basis eines Arbeitsvertrags<\/li>\n<li>P\u00fcnktliche Gehaltszahlungen und attraktive Boni<\/li>\n<li>Gut gewarteter Fuhrpark<\/li>\n<\/ul>\n<ul>\n<li>Sozialversicherung und zus\u00e4tzliche Sozialleistungen<\/li>\n<li>Freundliche Atmosph\u00e4re in einem zusammenhaltenden Team<\/li>\n<\/ul>\n","protected":false},"author":20087,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-269714","job_listing","type-job_listing","status-expired","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"UL-TRANS PRZEMYS\u0141AW ULANOWSKI","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-ul-trans-przemyslaw-ulanowski\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/269714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/20087"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=269714"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/269714\/revisions"}],"predecessor-version":[{"id":563481,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/269714\/revisions\/563481"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=269714"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=269714"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=269714"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=269714"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=269714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}