{"id":267673,"date":"2026-01-12T01:00:09","date_gmt":"2026-01-12T01:00:09","guid":{"rendered":"https:\/\/driver-work.com\/job\/kierowca-kat-ce-lokalny\/"},"modified":"2026-07-12T00:32:24","modified_gmt":"2026-07-12T00:32:24","slug":"job-266872","status":"expired","type":"job_listing","link":"https:\/\/driver-work.com\/de\/?post_type=job_listing&p=267673","title":{"rendered":"Kierowca kat. C+E lokalny"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Schichtarbeit: nein<\/li>\n<li>Arbeitstage: Werktage (Montag &#8211; Freitag)<\/li>\n<li>M\u00f6gliche Nachtarbeit: nein<\/li>\n<li>Auszahlungsmodus: monatlich<\/li>\n<\/ul>\n<h5>Dein Aufgabenbereich:<\/h5>\n<ul>\n<li>F\u00fchren eines C+E-Gespanns<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>Gewissenhaftigkeit<\/li>\n<li>Erfahrung auf C+E mindestens ein Jahr<\/li>\n<\/ul>\n<h6>W\u00fcnschenswert:<\/h6>\n<ul>\n<li>W\u00fcnschenswert ist jemand Normales<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Festanstellung<\/li>\n<li>Einfaches Abrechnungssystem (Tagespauschale)<\/li>\n<li>Die meisten Verladungen von hinten<\/li>\n<\/ul>\n<ul>\n<li>Fahren nach festen Punkten (zu 80-90%)<\/li>\n<li>Technisch einwandfreie Fahrzeuge (das ist eher normal, aber dennoch nicht \u00fcberall anzutreffen)<\/li>\n<\/ul>\n","protected":false},"author":22338,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-267673","job_listing","type-job_listing","status-expired","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"PAS TRANS US\u0141UGI TRANSPORTOWE WOJCIECH PASIEKA I MATEUSZ PASIEKA s.c.","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-pas-trans-uslugi-transportowe-wojciech-pasieka-i-mateusz-pasieka-s-c\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/267673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/22338"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=267673"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/267673\/revisions"}],"predecessor-version":[{"id":561667,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/267673\/revisions\/561667"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=267673"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=267673"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=267673"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=267673"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=267673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}