{"id":267475,"date":"2026-01-12T01:01:48","date_gmt":"2026-01-12T01:01:48","guid":{"rendered":"https:\/\/driver-work.com\/job\/ce-fahrer-fur-inlandsrouten\/"},"modified":"2026-07-12T00:31:41","modified_gmt":"2026-07-12T00:31:41","slug":"job-266806","status":"expired","type":"job_listing","link":"https:\/\/driver-work.com\/de\/?post_type=job_listing&p=267475","title":{"rendered":"C+E Fahrer f\u00fcr Inlandsrouten"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Arbeitstage: Wochentage (Montag &#8211; Freitag)<\/li>\n<li>Zahlungsmethode: monatlich<\/li>\n<\/ul>\n<h5>Ihre Aufgaben:<\/h5>\n<ul>\n<li>Wir suchen Fahrer f\u00fcr die Route: \u015awiecie &#8211; Mszczon\u00f3w<\/li>\n<li>Fahren eines Fahrzeugs der Kategorie C+E<\/li>\n<li>Durchf\u00fchrung von Inlandsrouten<\/li>\n<li>Sorgfalt im Umgang mit der anvertrauten Ausr\u00fcstung<\/li>\n<li>Durchf\u00fchrung von Transportaufgaben<\/li>\n<li>Vollzeitstelle<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>C+E-F\u00fchrerschein<\/li>\n<li>Berufserfahrung<\/li>\n<li>Abgeschlossener Kurs f\u00fcr den G\u00fctertransport<\/li>\n<li>Bereitschaft zur langfristigen Zusammenarbeit<\/li>\n<li>Erfahrung im Fahren eines bestimmten Fahrzeugtyps<\/li>\n<li>Besitz der entsprechenden Qualifikationen f\u00fcr den G\u00fctertransport<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Arbeit in einem geschlossenen und unterst\u00fctzenden Team<\/li>\n<li>P\u00fcnktliche Gehaltszahlung<\/li>\n<li>Stabile Anstellung auf Basis eines Arbeitsvertrags<\/li>\n<li>Aussicht auf langfristige Zusammenarbeit<\/li>\n<li>Arbeit von Montag bis Freitag<\/li>\n<\/ul>\n<ul>\n<li>Abfahrten und R\u00fcckkehr nach \u015awiecie<\/li>\n<li>Dem Mitarbeiter zugewiesenes Fahrzeug<\/li>\n<li>Volle Sozialversicherung (ZUS)<\/li>\n<li>Feste Routen<\/li>\n<\/ul>\n","protected":false},"author":22923,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-267475","job_listing","type-job_listing","status-expired","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Zak\u0142ad Handlowo-Us\u0142ugowo-Transportowy &#8211; s.c. Eliza Patrycja Szreiber Marcin Adam Michta","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-zaklad-handlowo-uslugowo-transportowy-s-c-eliza-patrycja-szreiber-marcin-adam-michta\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/267475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/22923"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=267475"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/267475\/revisions"}],"predecessor-version":[{"id":561568,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/267475\/revisions\/561568"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=267475"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=267475"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=267475"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=267475"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=267475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}