{"id":260486,"date":"2026-01-06T01:03:00","date_gmt":"2026-01-06T01:03:00","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-ce\/"},"modified":"2026-07-06T00:30:42","modified_gmt":"2026-07-06T00:30:42","slug":"job-260032","status":"expired","type":"job_listing","link":"https:\/\/driver-work.com\/de\/?post_type=job_listing&p=260486","title":{"rendered":"LKW-Fahrer C+E"},"content":{"rendered":"<h5>Zus\u00e4tzliche Informationen:<\/h5>\n<ul>\n<li>Schichtarbeit: nein<\/li>\n<li>Arbeitstage: Werktage (Montag &#8211; Freitag), Samstag<\/li>\n<li>M\u00f6gliche Nachtarbeit: nein<\/li>\n<li>Auszahlungsmodus: monatlich<\/li>\n<\/ul>\n<h5>Ihr Aufgabenbereich:<\/h5>\n<ul>\n<li>Wir suchen einen erfahrenen Fahrer der Kategorie C+E<\/li>\n<\/ul>\n<h5>Unsere Anforderungen:<\/h5>\n<ul>\n<li>F\u00fchrerschein Kat. C+E<\/li>\n<li>Bef\u00e4higungsnachweis<\/li>\n<li>Erfahrung im G\u00fctertransport min. 1 Jahr<\/li>\n<li>Erfahrung im F\u00fchren von vierachsigen Fahrzeugen<\/li>\n<li>Verantwortungsbewusstsein, P\u00fcnktlichkeit und gute Arbeitsorganisation<\/li>\n<\/ul>\n<h5>Wir bieten:<\/h5>\n<ul>\n<li>Attraktive Verg\u00fctung<\/li>\n<li>Stabile Anstellungsbedingungen auf Basis eines Arbeitsvertrags<\/li>\n<\/ul>\n<ul>\n<li>Interessenten werden gebeten, ihren Lebenslauf \u00fcber pracuj.pl einzusenden<\/li>\n<li>Das Gehalt ist je nach Erfahrung und F\u00e4higkeiten verhandelbar<\/li>\n<\/ul>\n","protected":false},"author":22235,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-260486","job_listing","type-job_listing","status-expired","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJuwtkpGSZAEcR6lXMScpzdQk","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"AUTO-BAU DANIEL BRY\u0141A","_job_employer_url":"https:\/\/driver-work.com\/de\/employer\/ext-auto-bau-daniel-bryla\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/260486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/users\/22235"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/comments?post=260486"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/260486\/revisions"}],"predecessor-version":[{"id":549611,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing\/260486\/revisions\/549611"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/media?parent=260486"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_type?post=260486"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_category?post=260486"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_location?post=260486"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/de\/wp-json\/wp\/v2\/job_listing_tag?post=260486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}