{"id":562749,"date":"2026-07-13T00:06:51","date_gmt":"2026-07-13T00:06:51","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-plateau-bois-et-marchandises-generales-h-f\/"},"modified":"2026-07-13T00:06:51","modified_gmt":"2026-07-13T00:06:51","slug":"job-562749","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-562749\/","title":{"rendered":"Chauffeur SPL plateau bois et marchandises g\u00e9n\u00e9rales H\/F"},"content":{"rendered":"<div id=\"shema_offre3\">\n<div>\n<p>\n                            <span><\/p>\n<p>Int\u00e9gr\u00e9 \u00e0 une \u00e9quipe de chauffeur \/ conducteur, vous serez rattach\u00e9 \u00e0 un gestionnaire des op\u00e9rations de transport.<\/p>\n<ul>\n<li><span>Vous conduirez un ensemble FMA plateau bois et marchandise g\u00e9n\u00e9rale en r\u00e9gional<\/span><\/li>\n<li><span>Vous r\u00e9aliserez les ordres de missions qui vous seront transmis par l\u2019exploitation dans le respect des r\u00e8gles de <strong>s\u00e9curit\u00e9<\/strong><\/span><\/li>\n<li><span>Vous serez l\u2019<strong>Ambassadeur<\/strong> du groupe MAUFFREY aupr\u00e8s des clients et des usagers de la route<\/span><\/li>\n<\/ul>\n<p>Contrat : CDI<\/p>\n<p>Si vous disposez :<\/p>\n<ul>\n<li>De votre Permis SPL (EC)<\/li>\n<li>De votre FIMO<\/li>\n<li>D\u2019une carte conducteur \u00e0 jour<\/li>\n<li>D\u2019une premi\u00e8re exp\u00e9rience dans le transport <strong>routier<\/strong> de marchandises<\/li>\n<li>Du sens du service client<\/li>\n<\/ul>\n<p>Alors ce poste est fait pour vous\u00a0!<\/p>\n<p> Devenir chauffeur \/ conducteur au sein du Groupe Mauffrey c&#8217;est :<br \/>&#8211; Conduire du mat\u00e9riel r\u00e9cent et renouvel\u00e9 tous les 4 ans<br \/>&#8211; \u00catre accompagn\u00e9 par un conducteur r\u00e9f\u00e9rent lors de votre int\u00e9gration et tout au long de votre vie professionnelle.<br \/>&#8211; Disposer de la technologie embarqu\u00e9e et des outils digitaux (smartphone, CMR \u00e9lectronique)<br \/>&#8211; Avoir des possibilit\u00e9s d&#8217;\u00e9volution interne et de mobilit\u00e9 g\u00e9ographique<br \/>&#8211; B\u00e9n\u00e9ficier d&#8217;avantages : primes diverses.<\/span>\n                        <\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"author":25751,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-562749","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"GROUPE MAUFFREY","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-groupe-mauffrey\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/562749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/25751"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=562749"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/562749\/revisions"}],"predecessor-version":[{"id":562750,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/562749\/revisions\/562750"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=562749"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=562749"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=562749"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=562749"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=562749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}