{"id":561118,"date":"2026-07-12T00:12:09","date_gmt":"2026-07-12T00:12:09","guid":{"rendered":"https:\/\/driver-work.com\/job\/kraftfahrer-lkw-fahrer-m-w-d\/"},"modified":"2026-07-12T00:12:09","modified_gmt":"2026-07-12T00:12:09","slug":"job-561118","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-561118\/","title":{"rendered":"Kraftfahrer\/LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Zur Verst\u00e4rkung unseres Rennteams suchen wir ab sofort eine\/n Kraftfahrer\/in mit Leidenschaft f\u00fcr den Motorsport, hoher Einsatzbereitschaft und technischem Verst\u00e4ndnis.<br \/>\nDein Aufgabengebiet:<\/p>\n<p>Europaweiter Transport unserer Rennfahrzeuge, Ersatzteile und Ausr\u00fcstung zu Test- und Rennveranstaltungen<br \/>\nAuf- und Abbau der gesamten Team-Infrastruktur an Rennstrecken<br \/>\nVorbereitung der Rennreifen w\u00e4hrend Test- und Rennveranstaltungen<br \/>\nWartung und Instandsetzung von Ausr\u00fcstung und Ersatzteilen<br \/>\nKontrolle von Lagerbest\u00e4nden sowie allgemeine Lagert\u00e4tigkeiten<br \/>\nPflege sowie kleinere Reparaturen an unserem LKW-Fuhrpark<\/p>\n<p>Das bringst Du mit:<\/p>\n<p>G\u00fcltiger F\u00fchrerschein Klasse CE\u00a0<br \/>\nBef\u00e4higung nach Berufskraftfahrer-Qualifikationsgesetz (Kennziffer 95)<br \/>\nGutes technisches Verst\u00e4ndnis rund um LKWs und PKWs<br \/>\nBerufserfahrungen im Bereich Transport\/Fahrzeugtechnik<br \/>\nSorgf\u00e4ltige, genaue und selbstst\u00e4ndigen Arbeitsweise<br \/>\nTeamf\u00e4higkeit, Engagement und hohe Leistungsbereitschaft<br \/>\nBereitschaft zu Reiset\u00e4tigkeit sowie Eins\u00e4tzen an Wochenenden<\/p>\n<p>Das erwartet Dich:<\/p>\n<p>Ein spannendes Aufgabenfeld im professionellen Motorsport<br \/>\nFlache Hierarchien und ein motiviertes Team<br \/>\nEin modernes Arbeitsumfeld und eine Betriebskantine<br \/>\nEine leistungsgerechte Verg\u00fctung und ein unbefristeter Arbeitsvertrag<br \/>\nArbeit an verschiedenen Einsatzorten, Haupteinsatzort ist Neusalza-Spremberg<\/p>\n<p>Jetzt bewerben!<br \/>\nWir freuen uns auf Deine Bewerbung mit Lebenslauf und der Angabe des fr\u00fchestm\u00f6glichen Eintrittsdatums, bevorzugt per E-Mail an<br \/>\npersonal@muennich-motorsport.com.<\/p>\n","protected":false},"author":22053,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-561118","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"M\u00fcnnich Motorsport GmbH","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-munnich-motorsport-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/561118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/22053"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=561118"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/561118\/revisions"}],"predecessor-version":[{"id":561119,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/561118\/revisions\/561119"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=561118"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=561118"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=561118"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=561118"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=561118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}