{"id":560813,"date":"2026-07-11T00:08:36","date_gmt":"2026-07-11T00:08:36","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-nuit-h-f\/"},"modified":"2026-07-11T00:08:36","modified_gmt":"2026-07-11T00:08:36","slug":"job-560813","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-560813\/","title":{"rendered":"Chauffeur PL Nuit (h\/f)"},"content":{"rendered":"<div>\n<p>Iziwork, l&#8217;agence d&#8217;int\u00e9rim digital #1, recherche un Chauffeur PL Nuit (h\/f) \u00e0 Montauban. Candidatez en un clic et acc\u00e9dez \u00e0 tous nos services depuis la meilleure app du march\u00e9.<\/p>\n<\/div>\n<div>\n<p>Notre client, sp\u00e9cialis\u00e9 dans le transport de marchandises, recherche un(e) Chauffeur PL.<\/p>\n<\/div>\n<p><strong>\u00c0 propos de la mission<\/strong><\/p>\n<div>\n<p>Rattach\u00e9(e) au responsable d&#8217;exploitation, vous serez en charge des missions suivantes :<\/p>\n<ul>\n<li>Conduire un camion poids lourd en toute s\u00e9curit\u00e9<\/li>\n<li>Utiliser le hayon pour le chargement et d\u00e9chargement des marchandises<\/li>\n<li>Assurer la livraison de magasins en r\u00e9gion, de nuit<\/li>\n<\/ul>\n<p>\n<\/div>\n<div>\n<p>Rythme de travail :<\/p>\n<\/div>\n<ul>\n<li>Travail de nuit<\/li>\n<\/ul>\n<p><strong>R\u00e9mun\u00e9ration &amp; Avantages<\/strong><\/p>\n<div>\n<p>R\u00e9mun\u00e9ration : 2\u202f600 \u20ac &#8211; 2\u202f800 \u20ac par mois<br \/>\n  Volume horaire hebdomadaire de base : 35 heures par semaine<br \/>\n  Avantages :<\/p>\n<ul>\n<li>10% d&#8217;indemnit\u00e9s de fin de mission (IFM) + 10% de prime de cong\u00e9s pay\u00e9s (CP), soit un salaire total brut de 3\u202f146,00\u20ac &#8211; 3\u202f388,00\u20ac par mois<\/li>\n<li>Demandes d&#8217;acompte en 24h<\/li>\n<li>Un des meilleurs CET de France avec un taux d&#8217;int\u00e9r\u00eat de 10% par an<\/li>\n<li>Tous vos services dans une application<\/li>\n<li>Acc\u00e8s rapide \u00e0 tous vos documents sur notre application<\/li>\n<li>Accompagnement de nos int\u00e9rimaires tout au long de leur carri\u00e8re avec notre service formation<\/li>\n<\/ul>\n<p>\n<\/div>\n<p><strong>Profil recherch\u00e9<\/strong><\/p>\n<ul>\n<li>Exp\u00e9rience : Au moins 1 mois<\/li>\n<\/ul>\n<p><strong>Certificats requis<\/strong><\/p>\n<ul>\n<li>Permis C &#8211; Poids lourd<\/li>\n<li>Carte de conducteur (chrono tachygraphe)<\/li>\n<li>Carte de qualification conducteur marchandise (FIMO\/FCO)<\/li>\n<\/ul>\n<p><\/p>\n<div>\n<p>Iziwork valorise la diversit\u00e9, l&#8217;\u00e9galit\u00e9 des chances et l&#8217;inclusion. Toutes les candidatures sont \u00e9tudi\u00e9es en fonction des aptitudes et comp\u00e9tences. Vos donn\u00e9es personnelles sont trait\u00e9es conform\u00e9ment \u00e0 notre politique de confidentialit\u00e9 disponible sur notre site ou sur demande \u00e0 *** Vous pouvez exercer vos droits conform\u00e9ment au RGPD en suivant la proc\u00e9dure d\u00e9crite dans celle-ci.<br \/>\n  ____<br \/>\n  Le versement de l&#8217;indemnit\u00e9 de cong\u00e9s pay\u00e9s (ICCP) se fait mensuellement. Le versement de l&#8217;indemnit\u00e9 de fin de mission (IFM) se fait \u00e0 l&#8217;issue de chaque mission effectivement accomplie, sous r\u00e9serve des cas de non-versement pr\u00e9vus \u00e0 l&#8217;article L1251-33 du Code du travail.<\/p>\n<\/div>\n","protected":false},"author":25874,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[171],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-560813","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-uk"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["C"],"_job_we_offer":"","_job_type":{"171":"\u041f\u043e\u0432\u043d\u0430 \u0437\u0430\u0439\u043d\u044f\u0442\u0456\u0441\u0442\u044c"},"_job_salary_type":"","_job_salary":"$2600 - $2800","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Iziwork","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-iziwork\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/560813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/25874"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=560813"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/560813\/revisions"}],"predecessor-version":[{"id":560814,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/560813\/revisions\/560814"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=560813"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=560813"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=560813"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=560813"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=560813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}