{"id":539160,"date":"2026-06-30T00:06:54","date_gmt":"2026-06-30T00:06:54","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-pl-et-agent-de-quai-h-f\/"},"modified":"2026-06-30T00:06:54","modified_gmt":"2026-06-30T00:06:54","slug":"job-539160","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-539160\/","title":{"rendered":"Chauffeur PL et Agent de quai H\/F"},"content":{"rendered":"<p>Dans le cadre du d\u00e9veloppement de son activit\u00e9, nous recherchons pour notre client, sp\u00e9cialis\u00e9 dans le secteur du transport et de la logistique, un chauffeur PL\/ agent de quai \u00e0 ATHIES &#8211; 62223.<br \/>\n<br \/>\nEn tant que chauffeur PL et agent de quai, les missions seront les suivantes :<br \/>\n<br \/>\n-60 \u00e0 70 % : op\u00e9rations d&#8217;accroche\/d\u00e9croche sur le parc, passage en station de lavage, ravitaillement du camion<br \/>\n<br \/>\n-30 \u00e0 40 % : activit\u00e9s d&#8217;agent de quai avec CACES R489 1 (chargement et d\u00e9chargement des camions)<br \/>\n<br \/>\n&#8211; Contrat en int\u00e9rim d&#8217;une dur\u00e9e d&#8217;une semaine renouvelable, embauche \u00e0 la cl\u00e9<br \/>\n<br \/>\n&#8211; Horaires de journ\u00e9e variables : de 11h30 \u00e0 20h20<br \/>\n<br \/>\nVous disposerez aussi des avantages CRIT :<br \/>\n<br \/>\n&#8211; Taux horaire fixe + 10% fin de mission + 10% cong\u00e9s pay\u00e9s.<br \/>\n<br \/>\n&#8211; Compte Epargne Temps (CET) d\u00e9blocable \u00e0 tout moment.<br \/>\n<br \/>\n&#8211; Acompte de paie hebdomadaire si besoin.<br \/>\n<br \/>\n&#8211; Aides diverses (via FASTT) : mutuelle, logement, garde d&#8217;enfants, etc.<br \/>\n<br \/>\n&#8211; Application My Crit pour un suivi facile.<br \/>\n<br \/>\n&#8211; Comit\u00e9 Social et \u00c9conomique (CSE) : cartes cadeaux, remboursement ch\u00e8ques vacances, etc.<br \/><\/p>\n","protected":false},"author":25741,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-539160","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["C"],"_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Crit","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-crit\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/539160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/25741"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=539160"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/539160\/revisions"}],"predecessor-version":[{"id":539161,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/539160\/revisions\/539161"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=539160"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=539160"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=539160"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=539160"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=539160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}