{"id":539134,"date":"2026-06-30T00:06:15","date_gmt":"2026-06-30T00:06:15","guid":{"rendered":"https:\/\/driver-work.com\/job\/chauffeur-spl-h-f\/"},"modified":"2026-06-30T00:06:15","modified_gmt":"2026-06-30T00:06:15","slug":"job-539134","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-539134\/","title":{"rendered":"Chauffeur SPL* H\/F"},"content":{"rendered":"<p><\/p>\n<p><em>Devenons co-\u00e9quipier dans votre projet professionnel et d\u00e9crochez un emploi durable gr\u00e2ce \u00e0 nous.<\/em><\/p>\n<p><strong>Aquila RH Cherbourg<\/strong> recherche pour l&#8217;un de ses clients un<strong> CHAUFFEUR SPL<\/strong> H\/F.<\/p>\n<p>Nos candidats sont des partenaires, nos ambassadeurs chez nos clients. Nous sommes soucieux de les accompagner \u00e0 chaque instant. Notre vocation est de faire le lien entre vous et les entreprises. Nous mettons nos valeurs au c\u0153ur de nos actions :<\/p>\n<ul>\n<li>la transparence<\/li>\n<li>l&#8217;engagement pour la performance<\/li>\n<li>l&#8217;\u00e9galit\u00e9 des chances.<\/li>\n<\/ul>\n<p>En rejoignant Aquila RH, vous b\u00e9n\u00e9ficierez des avantages suivants :<\/p>\n<ul>\n<li>\u2705Acomptes vers\u00e9s deux fois par semaine, les mardis et jeudis, pour une meilleure gestion de votre budget.<\/li>\n<li>\u2705Indemnit\u00e9s de fin de mission et cong\u00e9s pay\u00e9s major\u00e9es de 10% per\u00e7ues tous les mois.<\/li>\n<li>\u2705Possibilit\u00e9 d&#8217;avance de tr\u00e9sorerie jusqu&#8217;\u00e0 100% de vos Indemnit\u00e9s de Fin de Mission et Indemnit\u00e9s Cong\u00e9s Pay\u00e9s.<\/li>\n<li>\u2705Votre \u00e9pargne r\u00e9mun\u00e9r\u00e9e \u00e0 5% par an d\u00e8s 2026, pour pr\u00e9parer sereinement votre avenir.<\/li>\n<li>\u2705Prime de fid\u00e9lit\u00e9 pouvant atteindre 200\u20ac en janvier 2027, pour r\u00e9compenser votre engagement et votre loyaut\u00e9.<\/li>\n<li>\u2705Acc\u00e8s \u00e0 notre partenaire Couleur CE d\u00e8s la 1\u00e8re heure de mission, pour b\u00e9n\u00e9ficier de r\u00e9ductions exclusives dans le domaine de la billetterie, des parcs et loisirs, de l&#8217;art et de la culture.<\/li>\n<li>\u2705Mutuelle d&#8217;entreprise et acc\u00e8s au FASTT : acc\u00e8s \u00e0 des formations, r\u00e9ductions sur les locations de voiture, acc\u00e8s prioritaire aux gardes d&#8217;enfant, et bien plus encore.<\/li>\n<\/ul>\n<p><\/p>\n<p>Vos missions<\/p>\n<p>Vos missions :<\/p>\n<ul>\n<li>conduire un v\u00e9hicule routier lourd<\/li>\n<li>pr\u00e9parer le camion avant le d\u00e9part et s&#8217;assurer de la conformit\u00e9 du camion<\/li>\n<li>effectuer le chargement ou veiller \u00e0 son bon d\u00e9roulement<\/li>\n<li>v\u00e9rifier la conformit\u00e9 de la livraison<\/li>\n<li>contr\u00f4ler le d\u00e9charment du camion<\/li>\n<li>assurer l&#8217;entretien du camion<\/li>\n<li>r\u00e9aliser les op\u00e9rations d&#8217;attelage<\/li>\n<\/ul>\n<p><\/p>\n","protected":false},"author":25731,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[478],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-539134","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-pl"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["CE"],"_job_we_offer":"","_job_type":{"478":"Praca na pe\u0142en etat"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Aquila RH","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-aquila-rh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/539134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/25731"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=539134"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/539134\/revisions"}],"predecessor-version":[{"id":539135,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/539134\/revisions\/539135"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=539134"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=539134"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=539134"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=539134"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=539134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}