{"id":531676,"date":"2026-06-22T00:08:57","date_gmt":"2026-06-22T00:08:57","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-06-22T00:08:57","modified_gmt":"2026-06-22T00:08:57","slug":"job-531676","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-531676\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Bruchsal<\/p>\n<p>** Im Folgenden wird der besseren Lesbarkeit halber \u00fcberwiegend die m\u00e4nnliche Form verwendet **<\/p>\n<p>F\u00fcr einen Einsatz, bei einem namhaften Industrieunternehmen, suchen wir \u00fcber die Arbeitnehmer\u00fcberlassung ab sofort:<\/p>\n<p>[LKW-Fahrer] (m\/w\/d)<\/p>\n<p>&#8211; eine erste R\u00fcckmeldung innerhalb 24 Stunden (Mo-Fr)!<br \/>\n&#8211; eine sozialversicherte Anstellung in Vollzeit!<br \/>\n&#8211; einen unbefristeten Arbeitsvertrag!<br \/>\n&#8211; einen attraktiven Arbeitsplatz in einem starken Mitarbeiter- und Kollegenteam!<br \/>\n&#8211; sehr gute \u00dcbernahmechancen in den Kundenunternehmen!<br \/>\n&#8211; Urlaubs-, Weihnachtsgeld und weitere Leistungspr\u00e4mien!<br \/>\n&#8211; jedes Mal eine Bonuszahlung von 750 \u20ac Brutto, wenn Sie uns erfolgreich weiter empfehlen<br \/>\n&#8211; pers\u00f6nliche Beratung und Betreuung bis hin zur \u00dcbernahme im Kundenunternehmen!<\/p>\n<p>Deine Aufgaben:<br \/>\n&#8211; Kontrollieren von Frachtpapieren<br \/>\n&#8211; Durchf\u00fchrung von Transporten<br \/>\n&#8211; Termingerechtes Liefern und Abholen von Ladegut<br \/>\n&#8211; Pflege des \u00fcberlassenen LKW\u00b4s<\/p>\n<p>Deine F\u00e4higkeiten:<br \/>\n&#8211; G\u00fcltiger F\u00fchrerschein der Klasse CE mit Schl\u00fcsselqual<\/p>\n","protected":false},"author":24949,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-531676","job_listing","type-job_listing","status-publish","hentry"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":[],"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"PLSH Personal-Logistik-Service Heilbronn GmbH","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-plsh-personal-logistik-service-heilbronn-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/531676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/24949"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=531676"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/531676\/revisions"}],"predecessor-version":[{"id":531677,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/531676\/revisions\/531677"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=531676"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=531676"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=531676"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=531676"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=531676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}