{"id":530928,"date":"2026-06-21T00:10:06","date_gmt":"2026-06-21T00:10:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-06-21T00:10:06","modified_gmt":"2026-06-21T00:10:06","slug":"job-530928","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-530928\/","title":{"rendered":"LKW-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Standort: Heilbronn<br \/>\nAnstellungsart(en): Vollzeit<br \/>\nArbeitszeit: 40 Stunden pro Woche<\/p>\n<p>F\u00fcr einen unserer Auftraggeber, einem regionalen Dienstleister der weltweit bekannt ist, stellen wir zum n\u00e4chstm\u00f6glichen Zeitpunkt ein:<\/p>\n<p>LKW-Fahrer (m\/w\/d)<\/p>\n<p>Sie bekommen:<br \/>\n&#8211; eine erste R\u00fcckmeldung innerhalb eines Tages (Mo-Fr)!<br \/>\n&#8211; eine sozialversicherte Anstellung in Vollzeit!<br \/>\n&#8211; einen unbefristeten Arbeitsvertrag!<br \/>\n&#8211; Urlaubs-, Weihnachtsgeld und weitere Leistungspr\u00e4mien!<br \/>\n&#8211; jedes Mal eine Bonuszahlung, wenn Sie uns erfolgreich weiter empfehlen!<\/p>\n<p>Ihre Aufgaben:<br \/>\n&#8211; \u00dcberpr\u00fcfen der Verkehrssicherheit des Fahrzeugs<br \/>\n&#8211; Als Lkw-Fahrer\/Berufskraftfahrer f\u00fchren Sie einen Sattelzug oder 12-Tonner im Nahverkehr<br \/>\n&#8211; Einhaltung von Ladungssicherung<br \/>\n&#8211; Mithilfe beim Be- und Entladen<\/p>\n<p>Ihre F\u00e4higkeiten:<br \/>\n&#8211; F\u00fchrerschein Klasse C\/CE und Fahrerkarte zwingend erforderlich<br \/>\n&#8211; erste Berufserfahrung als Kraftfahrer (m\/w\/d) w\u00fcnschenswert, aber auch Quereinsteiger willkommen<br \/>\n&#8211; sicheres und verantwortungsvolles Verhalten im Stra\u00dfenverkehr<br \/>\n&#8211; teamf\u00e4hig, zuverl\u00e4ssig und gewissenhaft<\/p>\n<p>PLS! Personal-Logistik-Service ist Spezialist f\u00fcr Arbeitnehmer\u00fcberlassung und professionelle Personalvermittlung. Weiter ist PLS! Mitglied der FRITZ-Gruppe, mit rund 700 Mitarbeitern eines der gr\u00f6\u00dften inhabergef\u00fchrten Speditions- und Logistikunternehmen in der Region Heilbronn. Wir verf\u00fcgen daher \u00fcber hervorragende Kontakte zu Industrie- und Handelsunternehmen und haben auch f\u00fcr Sie den Traumjob!<\/p>\n<p>Bewerben Sie sich gleich bei PLS! und profitieren Sie von den Kompetenzen dieser wachsenden Gemeinschaft!<\/p>\n<p>F\u00fcr Ihre Fragen steht Ihnen Herr Haaf unter 07131\/591580 zur Verf\u00fcgung. Vereinbaren Sie telefonisch ein pers\u00f6nliches Beratungsgespr\u00e4ch oder kommen Sie einfach in unserer Niederlassung vorbei.<\/p>\n<p>Auf Ihre Bewerbung, bevorzugt online, unter Angabe der Referenznummer, freuen wir uns!<\/p>\n<p>Herr Nicky Haaf<\/p>\n<p>Deutschhofstra\u00dfe 23<\/p>\n<p>74072 Heilbronn<\/p>\n<p>+49 7131 591580<\/p>\n<p>E-Mail: bewerbungen@plsh.de<br \/>\nTarifvertrag: BAP<br \/>\nEntgeltgruppe: \u00fcbertariflich, je nach Qualifikation<\/p>\n","protected":false},"author":24950,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-530928","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"PLSH Personal-Logistik- Service Heilbronn GmbH","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-plsh-personal-logistik-service-heilbronn-gmbh-2\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/530928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/24950"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=530928"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/530928\/revisions"}],"predecessor-version":[{"id":530929,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/530928\/revisions\/530929"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=530928"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=530928"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=530928"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=530928"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=530928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}