{"id":489238,"date":"2026-05-29T00:13:45","date_gmt":"2026-05-29T00:13:45","guid":{"rendered":"https:\/\/driver-work.com\/job\/berufskraftfahrer-lkw-fahrer-m-w-d\/"},"modified":"2026-05-29T00:13:45","modified_gmt":"2026-05-29T00:13:45","slug":"job-489238","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-489238\/","title":{"rendered":"BERUFSKRAFTFAHRER \/ LKW-FAHRER (M\/W\/D)"},"content":{"rendered":"<p>Die BKL Baukran Logistik GmbH z\u00e4hlt seit \u00fcber 50 Jahren europaweit zu den f\u00fchrenden Anbietern f\u00fcr Kranl\u00f6sungen und verf\u00fcgt \u00fcber einen der gr\u00f6\u00dften und modernsten Kranparks Europas. Unseren Erfolg verdanken wir unseren rund 350 Mit\u00adarbeitern an unseren 9\u00a0Standorten in Deutschland.<\/p>\n<p>Zur Verst\u00e4rkung unseres Teams suchen wir mehrere<\/p>\n<p>BERUFSKRAFTFAHRER \/ LKW-FAHRER (M\/W\/D)<\/p>\n<p>DAS SIND IHRE T\u00c4TIGKEITEN<\/p>\n<p>\t* Fahren und \u00dcbernahme eines firmeneigenen LKWs<br \/>\n\t* Transport von Kranteilen und Kranballast vom Firmengel\u00e4nde zu Baustellen in der Region<br \/>\n\t* Verantwortung f\u00fcr die Pflege, Wartung und den technisch einwandfreien Zustand des Fahrzeugs<br \/>\n\t* Terminabstimmung und Einsatzplanung in enger Zusammenarbeit mit unserer Disposition<\/p>\n<p>DAS BRINGEN SIE MIT<\/p>\n<p>\t* F\u00fchrerschein der Klasse CE inkl. g\u00fcltiger Schl\u00fcsselzahl 95<br \/>\n\t* Einschl\u00e4gige Berufserfahrung im Schwerlastverkehr<br \/>\n\t* Idealerweise Erfahrungen im Umgang mit Kranen und Anh\u00e4ngern.<br \/>\n\t* Technisches Verst\u00e4ndnis und ein sicherer Umgang mit Fahrzeugtechnik<br \/>\n\t* Zuverl\u00e4ssige, selbstst\u00e4ndige und teamorientierte Arbeitsweise<\/p>\n<p>UNSERE LEISTUNGEN F\u00dcR SIE<\/p>\n<p>\t* Sicherheit &amp; Perspektive:\u00a0Unbefristete Vollzeitstelle in einem erfolgreichen, familiengef\u00fchrten Unternehmen mit pers\u00f6nlichem Umgang auf Augenh\u00f6he<br \/>\n\t* Leistungsgerechte Bezahlung:\u00a0Attraktive Zuschl\u00e4ge, Spesen und bezahlte \u00dcberstunden \u2013 zuverl\u00e4ssig und transparent abgerechnet<br \/>\n\t* Flexibles Arbeitszeitkonto:\u00a0Bis zu 100 \u00dcberstunden ansammeln und nach Absprache in zus\u00e4tzliche freie Tage umwandeln<br \/>\n\t* Work-Life-Balance:\u00a037,5-Stunden-Woche, 27\u00a0Urlaubstage sowie Sonderurlaub bei besonderen Anl\u00e4ssen (z.B. Hochzeit oder Geburt)<br \/>\n\t* Moderner Fuhrpark:\u00a0Einsatz modernster Maschinen und Fahrzeuge f\u00fcr komfortables und sicheres Arbeiten<br \/>\n\t* Finanzielle Extras:\u00a0Monatlicher steuerfreier Sachbezug sowie Zuschuss zur betrieblichen Altersvorsorge<br \/>\n\t* Nachhaltige Mobilit\u00e4t:\u00a0M\u00f6glichkeit zum JobRad-Leasing \u2013 selbstverst\u00e4ndlich auch f\u00fcr private Fahrten<br \/>\n\t* Moderne Arbeitsmittel:\u00a0iPhone und iPad zur gesch\u00e4ftlichen und privaten Nutzung<br \/>\n\t* Wertsch\u00e4tzendes Miteinander:\u00a0Kollegiales Team, flache Hierarchien und offene Kommunikationskultur<\/p>\n<p>HABEN WIR IHR INTERESSE GEWECKT?<\/p>\n<p>Dann freuen wir uns auf Ihre Bewerbung \u00fcber unser Bewerbungsformular\u00a0www.bkl.de\/bewerbungsformular [https:\/\/www.bkl.de\/bewerbungsformular]<\/p>\n<p>Referenznummer: LKW2026<\/p>\n<p>BKL Baukran Logistik GmbH <\/p>\n<p>Frau Nicolette Volz, Leitung Personal<br \/>\nTel.: +4981212248187<br \/>\n bewerbung@bkl.de<br \/>\n [https:\/\/www.bkl.de\/bewerbungsformular\/]<\/p>\n","protected":false},"author":14589,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-489238","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"BKL Baukran Logistik GmbH","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-bkl-baukran-logistik-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/489238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/14589"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=489238"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/489238\/revisions"}],"predecessor-version":[{"id":489239,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/489238\/revisions\/489239"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=489238"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=489238"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=489238"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=489238"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=489238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}