{"id":487165,"date":"2026-05-27T00:12:27","date_gmt":"2026-05-27T00:12:27","guid":{"rendered":"https:\/\/driver-work.com\/job\/lkw-fahrer-m-w-d\/"},"modified":"2026-05-27T00:12:27","modified_gmt":"2026-05-27T00:12:27","slug":"job-487165","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-487165\/","title":{"rendered":"Lkw-Fahrer (m\/w\/d)"},"content":{"rendered":"<p>Wir sind Trio Personalmanagement\u2014 Dein regionaler Personaldienstleister<\/p>\n<p>Die gesamte Gesch\u00e4ftsf\u00fchrung, Mitarbeiterinnen und Mitarbeiter bringen langj\u00e4hrige Erfahrung in den Bereichen Arbeitnehmer\u00fcberlassung, Personalvermittlung, Vertrieb, Customer Service, Recruiting und Employee Care mit und leben Ihre Arbeit mit einer sehr ausgepr\u00e4gten Dienstleistungsmentalit\u00e4t.<\/p>\n<p>Zur Unterst\u00fctzung unseres Kunden<\/p>\n<p>in Forst<\/p>\n<p>suchen wir Dich als<\/p>\n<p>Lkw-Fahrer (m\/w\/d) <\/p>\n<p>Standort: Forst<br \/>\nAnstellungsart(en): Vollzeit<br \/>\nArbeitszeit: 35 &#8211; 40 Stunden pro Woche<\/p>\n<p>Deine Aufgaben:<br \/>\n&#8211; Fahren von Lkw f\u00fcr den Transport von Waren und G\u00fctern<br \/>\n&#8211; Sicherstellung der ordnungsgem\u00e4\u00dfen Beladung und Entladung<br \/>\n&#8211; Kontrolle der Ladungssicherung<br \/>\n&#8211; Einhaltung der Verkehrs- und Sicherheitsvorschriften<br \/>\n&#8211; Pflege und Wartung des Fahrzeugs<br \/>\n&#8211; Dokumentation der Fahrten und \u00dcbergabe von Transportpapieren<br \/>\n&#8211; Ansprechpartner f\u00fcr Kunden und Kollegen vor Ort<\/p>\n<p>Dein Profil:<br \/>\n&#8211; G\u00fcltiger Lkw-F\u00fchrerschein (Klasse C\/CE)<br \/>\n&#8211; Erfahrung im Fahren von Lkw und im Umgang mit Transportfahrzeugen<br \/>\n&#8211; Gute Deutschkenntnisse in Wort und Schrift<br \/>\n&#8211; Zuverl\u00e4ssigkeit, P\u00fcnktlichkeit und Verantwortungsbewusstsein<br \/>\n&#8211; Teamf\u00e4higkeit und eine selbstst\u00e4ndige Arbeitsweise<br \/>\n&#8211; Bereitschaft zu flexiblen Arbeitszeiten<\/p>\n<p>Unser Angebot:<br \/>\n&#8211; Ein attraktives Verg\u00fctungspaket und Sonderzahlungen<br \/>\n&#8211; Eine langfristig gesicherte Perspektive mit Option auf \u00dcbernahme<br \/>\n&#8211; Abwechslungsreiche und interessante T\u00e4tigkeit<br \/>\n&#8211; Eins\u00e4tze in Deiner N\u00e4he<br \/>\n&#8211; Tarifliche Zuschl\u00e4ge (100 % Feiertagszulage, 50% Sonntagszulage, 25% Nachtzulage, 25% \u00dcberstundenzuschl\u00e4ge)<br \/>\n&#8211; Pers\u00f6nliche, qualifizierte und mehrsprachige (z.B. polnisch, mazedonisch, serbokroatisch, t\u00fcrkisch, italienisch, etc.) Betreuung<br \/>\n&#8211; Weiterbildungsm\u00f6glichkeiten<br \/>\n&#8211; Attraktive Sozialleistungen<br \/>\n&#8211; Fair Treatment<\/p>\n<p>Wir alle sind regional-pers\u00f6nlich-TRIO<\/p>\n<p>Haben wir Dein Interesse geweckt?<br \/>\nDann freuen wir uns auf Deine Bewerbung oder Deinen Besuch im Trio-Office in Bretten. Bitte sende uns Deine vollst\u00e4ndigen Bewerbungsunterlagen mit m\u00f6glichem Eintrittstermin und Deiner Gehaltsvorstellung, bevorzugt per E-Mail, zu.<\/p>\n<p>Wir bieten Voll-und Teilzeit Stellen unter anderem in folgenden Bereichen:<\/p>\n<p>Metall, Maschinenbau, Dienstleistung, Gesundheit, Soziales, P\u00e4dagogik, Elektro, Produktion, Fertigung, Verkehr, Logistik, Lager, Wirtschaft, Verwaltung<\/p>\n<p>Besuche uns auch auf www.trio-personal.de, Facebook und Instagram<\/p>\n<p>Kontakt:<\/p>\n<p>Trio Personalmanagement<\/p>\n<p>Engelsberg 12, 75015 Bretten<br \/>\n+49 7252 974 21 60<br \/>\nbretten@trio-personal.de<\/p>\n<p>Abteilung(en): LKW-Fahrer<br \/>\nArt(en) des Personalbedarfs: Neubesetzung<br \/>\nTarifvertrag: GVP<\/p>\n","protected":false},"author":14105,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[487],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-487165","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time-nl"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJa76xwh5ymkcRW-WRjmtd6HU","_job_required_languages":"","_job_driving_license":"","_job_we_offer":"","_job_type":{"487":"Voltijdwerk"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"Trio Personalmanagement GmbH","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-trio-personalmanagement-gmbh\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/487165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/14105"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=487165"}],"version-history":[{"count":1,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/487165\/revisions"}],"predecessor-version":[{"id":487166,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/487165\/revisions\/487166"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=487165"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=487165"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=487165"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=487165"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=487165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}