{"id":416337,"date":"2026-04-18T00:09:06","date_gmt":"2026-04-18T00:09:06","guid":{"rendered":"https:\/\/driver-work.com\/job\/conducteur-spl-avec-citerne-h-f\/"},"modified":"2026-04-18T00:09:06","modified_gmt":"2026-04-18T00:09:06","slug":"job-416337","status":"publish","type":"job_listing","link":"https:\/\/driver-work.com\/da\/job\/job-416337\/","title":{"rendered":"conducteur SPL avec citerne (H\/F)"},"content":{"rendered":"<p>INTERACTION PORT JEROME recherche pour le compte de son client, un conducteur SPL avec citerne pour une mission en int\u00e9rim.<br \/>\n<br \/>\nNous vous proposons de rejoindre une \u00e9quipe dynamique et de travailler pour une entreprise reconnue dans le secteur du transport. Vous serez en charge de la conduite d&#8217;un camion SPL \u00e9quip\u00e9 d&#8217;une citerne pour assurer la livraison de marchandises en toute s\u00e9curit\u00e9.<br \/>\n<br \/>\nVos missions :<br \/>\n<br \/>\n-Assurer le transport et la livraison de marchandises en citerne.<br \/>\n<br \/>\n-Veiller \u00e0 la s\u00e9curit\u00e9 des chargements et au respect des normes de s\u00e9curit\u00e9.<br \/>\n<br \/>\n-Effectuer les contr\u00f4les n\u00e9cessaires avant et apr\u00e8s chaque livraison.<br \/>\n<br \/>\n-Remplir les documents administratifs li\u00e9s au transport.<br \/>\n<br \/>\n-Assurer la propret\u00e9 et l&#8217;entretien du v\u00e9hicule.<br \/><\/p>\n","protected":false},"author":25921,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","job_listing_type":[67],"job_listing_category":[],"job_listing_location":[],"job_listing_tag":[],"class_list":["post-416337","job_listing","type-job_listing","status-publish","hentry","job_listing_type-full-time"],"aioseo_notices":[],"metas":{"_job_country_picker":"ChIJMVd4MymgVA0R99lHx5Y__Ws","_job_required_languages":"","_job_driving_license":["CE"],"_job_we_offer":"","_job_type":{"67":"Full time work"},"_job_salary_type":"","_job_salary":"","_job_experience":"","_job_video_url":"","_job_photos":"","_job_application_deadline_date":"","_job_employer_name":"INTERACTION","_job_employer_url":"https:\/\/driver-work.com\/da\/employer\/ext-interaction\/"},"_links":{"self":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/416337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing"}],"about":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/users\/25921"}],"replies":[{"embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/comments?post=416337"}],"version-history":[{"count":0,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing\/416337\/revisions"}],"wp:attachment":[{"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/media?parent=416337"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_type?post=416337"},{"taxonomy":"job_listing_category","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_category?post=416337"},{"taxonomy":"job_listing_location","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_location?post=416337"},{"taxonomy":"job_listing_tag","embeddable":true,"href":"https:\/\/driver-work.com\/da\/wp-json\/wp\/v2\/job_listing_tag?post=416337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}